{"id":6808,"date":"2021-04-04T16:16:31","date_gmt":"2021-04-04T16:16:31","guid":{"rendered":"https:\/\/vprspanishtranslations.com\/?p=6808"},"modified":"2023-02-14T17:37:18","modified_gmt":"2023-02-14T17:37:18","slug":"que-es-un-traductor-jurado","status":"publish","type":"post","link":"https:\/\/vprspanishtranslations.com\/es\/que-es-un-traductor-jurado\/","title":{"rendered":"\u00bfQu\u00e9 es un traductor jurado?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No todos los pa\u00edses cuentan con un sistema de traducci\u00f3n jurada como Espa\u00f1a, Francia o Italia. Es el caso, por ejemplo del Reino Unido. \u00bfPero <strong>qu\u00e9 es un traductor jurado<\/strong> y cu\u00e1les son los requisitos para serlo? En esta entrada explico estos y otros aspectos de la <strong>traducci\u00f3n jurada<\/strong>. <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/vprspanishtranslations.com\/wp-content\/uploads\/2020\/11\/quill-pen-2431674_1920-683x1024.jpg\" alt=\"Sworn Spanish Translator - Qu\u00e9 es un traductor jurado\" class=\"wp-image-5807\" width=\"258\" height=\"386\" srcset=\"https:\/\/vprspanishtranslations.com\/wp-content\/uploads\/2020\/11\/quill-pen-2431674_1920-683x1024.jpg 683w, https:\/\/vprspanishtranslations.com\/wp-content\/uploads\/2020\/11\/quill-pen-2431674_1920-200x300.jpg 200w, https:\/\/vprspanishtranslations.com\/wp-content\/uploads\/2020\/11\/quill-pen-2431674_1920-768x1152.jpg 768w, https:\/\/vprspanishtranslations.com\/wp-content\/uploads\/2020\/11\/quill-pen-2431674_1920-1024x1536.jpg 1024w, https:\/\/vprspanishtranslations.com\/wp-content\/uploads\/2020\/11\/quill-pen-2431674_1920.jpg 1280w\" sizes=\"(max-width: 258px) 100vw, 258px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es un traductor jurado?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En Espa\u00f1a, un traductor jurado es un ling\u00fcista nombrado por el Ministerio de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n y habilitado para traducir documentos oficiales o jur\u00eddicos, as\u00ed como para la interpretaci\u00f3n jurada. Un traductor jurado puede traducir tanto a espa\u00f1ol como a la lengua de nombramiento (por ejemplo, el ingl\u00e9s, en el caso del traductor jurado de ingl\u00e9s).  <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Or\u00edgenes de la traducci\u00f3n jurada en Espa\u00f1a<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque las fechas exactas se desconocen, existen registros que confirman que los traductores e int\u00e9rpretes comenzaron a ejercer a t\u00edtulo oficial durante la colonizaci\u00f3n espa\u00f1ola de Am\u00e9rica, lo que permiti\u00f3 la comunicaci\u00f3n entre los nativos y los conquistadores. El primer documento oficial donde se detalla el reglamento para las traducciones data de 1783. <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 documentos traducen los traductores jurados?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los traductores jurados traducen documentos jur\u00eddicos, acad\u00e9micos, personales y administrativos, como documentos de identidad, pasaportes, partidas de nacimiento, permisos de conducci\u00f3n, actas de constituci\u00f3n y estatutos sociales, testamentos, contratos o instrumentos de fideicomiso o <em>trust<\/em>, etc. <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfEs lo mismo un traductor jurado que un traductor jur\u00eddico?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No son t\u00e9rminos equivalentes. Si bien los traductores jurados est\u00e1n habilitados para traducir documentos jur\u00eddicos, su labor no se ci\u00f1e a este tipo de textos. Adem\u00e1s, se aconseja estudiar o saber de Derecho o traducci\u00f3n jur\u00eddica, dada la compleja naturaleza de este tipo de documentos.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 aspecto tiene una traducci\u00f3n jurada?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una traducci\u00f3n jurada va revestida del sello y la firma del traductor jurado, as\u00ed como de una certificaci\u00f3n que acredita que la traducci\u00f3n es fiel al original. Si la traducci\u00f3n es directa, la certificaci\u00f3n solamente ir\u00e1 en espa\u00f1ol. En el caso de la traducci\u00f3n inversa, la certificaci\u00f3n ir\u00e1 tanto en la lengua de partida como en la lengua de llegada. Por ejemplo, una traducci\u00f3n inversa (es decir, de espa\u00f1ol a ingl\u00e9s) realizada por un traductor jurado de ingl\u00e9s llevar\u00e1 una certificaci\u00f3n en espa\u00f1ol y en ingl\u00e9s.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 se exige para el nombramiento de traductores jurados en Espa\u00f1a?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Anteriormente, hab\u00eda dos v\u00edas para ser nombrado traductor jurado en Espa\u00f1a. Aparte de ser ciudadano espa\u00f1ol, el interesado <strong>deb\u00eda estar en posesi\u00f3n de un t\u00edtulo de Licenciado\/a en Traducci\u00f3n e Intepretaci\u00f3n<\/strong> y haber cursado la <strong>asignatura de traducci\u00f3n jur\u00eddico-financiera en los idiomas de inter\u00e9s<\/strong> como parte de dichos estudios de licenciatura. La otra forma de acceder consist\u00eda en superar un examen convocado por el Ministerio de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n. Actualmente, solo se puede acceder a la profesi\u00f3n de traducci\u00f3n jurada si se supera dicho examen.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfNecesita un traductor jurado de ingl\u00e9s?<\/strong> <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Yo soy traductor jurado de ingl\u00e9s nombrado por el <a href=\"https:\/\/www.exteriores.gob.es\/\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/www.exteriores.gob.es\/\" rel=\"noreferrer noopener\">Ministerio de Asuntos Exteriores<\/a> en 2003 (n.\u00ba 4057). <strong>Ofrezco traducciones juradas en Espa\u00f1a y el Reino Unido<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00f3ngase en contacto conmigo <a href=\"https:\/\/vprspanishtranslations.com\/es\/contacto\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FUENTES<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cristina Canahuati, <em><a href=\"https:\/\/presencia.unah.edu.hn\/noticias\/la-importancia-de-la-traduccion-en-la-colonizacion-de-los-pueblos\/\" data-type=\"URL\" data-id=\"https:\/\/presencia.unah.edu.hn\/noticias\/la-importancia-de-la-traduccion-en-la-colonizacion-de-los-pueblos\/\" target=\"_blank\" rel=\"noreferrer noopener\">La importancia de la traducci\u00f3n en la colonizaci\u00f3n de los pueblos<\/a><\/em><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>No todos los pa\u00edses cuentan con un sistema de traducci\u00f3n jurada como Espa\u00f1a, Francia o Italia. Es el caso, por ejemplo del Reino Unido. \u00bfPero qu\u00e9 es un traductor jurado y cu\u00e1les son los requisitos para serlo? En esta entrada explico estos y otros aspectos de la traducci\u00f3n jurada. \u00bfQu\u00e9 es un traductor jurado? En&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[198,23,28],"tags":[],"class_list":["post-6808","post","type-post","status-publish","format-standard","hentry","category-posts-in-english-es","category-sin-categorizar","category-traducciones-juradas"],"modified_by":"Virginia P\u00e9rez Rom\u00e1n BA GDL MCIL CL","uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"sow-carousel-default":false},"uagb_author_info":{"display_name":"Virginia P\u00e9rez Rom\u00e1n BA GDL MCIL CL","author_link":"https:\/\/vprspanishtranslations.com\/es\/author\/wp_abg3bp\/"},"uagb_comment_info":3,"uagb_excerpt":"No todos los pa\u00edses cuentan con un sistema de traducci\u00f3n jurada como Espa\u00f1a, Francia o Italia. Es el caso, por ejemplo del Reino Unido. \u00bfPero qu\u00e9 es un traductor jurado y cu\u00e1les son los requisitos para serlo? En esta entrada explico estos y otros aspectos de la traducci\u00f3n jurada. \u00bfQu\u00e9 es un traductor jurado? En&hellip;","_links":{"self":[{"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/posts\/6808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/comments?post=6808"}],"version-history":[{"count":14,"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/posts\/6808\/revisions"}],"predecessor-version":[{"id":10241,"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/posts\/6808\/revisions\/10241"}],"wp:attachment":[{"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/media?parent=6808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/categories?post=6808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vprspanishtranslations.com\/es\/wp-json\/wp\/v2\/tags?post=6808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}